{"id":278,"date":"2024-10-07T10:13:50","date_gmt":"2024-10-07T10:13:50","guid":{"rendered":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/"},"modified":"2026-04-23T21:16:50","modified_gmt":"2026-04-23T21:16:50","slug":"header-dark","status":"publish","type":"wcf-addons-template","link":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/","title":{"rendered":"Header Dark"},"featured_media":0,"template":"elementor_canvas","class_list":["post-278","wcf-addons-template","type-wcf-addons-template","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Header Dark - Reutlingen | T\u00fcbingen | Stuttgart<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Header Dark - Reutlingen | T\u00fcbingen | Stuttgart\" \/>\n<meta property=\"og:description\" content=\"Back \u00dcber uns Leistungen Haarstyling Preise Kontakt +49 000 000000 Hinter Tyler Smiths l\u00e4ssiger Surfer-Attit\u00fcde verbirgt sich eine starke Arbeitsmoral, die ihm weit \u00fcber das Haarstyling hinaus einen Namen gemacht hat. Galerie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/\" \/>\n<meta property=\"og:site_name\" content=\"Reutlingen | T\u00fcbingen | Stuttgart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T21:16:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/demos.infobd.de\/design4\/wp-content\/uploads\/sites\/8\/2024\/10\/demo-design-white.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"115\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/\",\"name\":\"Header Dark - Reutlingen | T\u00fcbingen | Stuttgart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/10\\\/demo-design-white.png\",\"datePublished\":\"2024-10-07T10:13:50+00:00\",\"dateModified\":\"2026-04-23T21:16:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/#primaryimage\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/10\\\/demo-design-white.png\",\"contentUrl\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/10\\\/demo-design-white.png\",\"width\":540,\"height\":115},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/wcf-template\\\/header-dark\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Header Dark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/#website\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/\",\"name\":\"Reutlingen | T\u00fcbingen | Stuttgart\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demos.infobd.de\\\/design4\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Header Dark - Reutlingen | T\u00fcbingen | Stuttgart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/","og_locale":"en_US","og_type":"article","og_title":"Header Dark - Reutlingen | T\u00fcbingen | Stuttgart","og_description":"Back \u00dcber uns Leistungen Haarstyling Preise Kontakt +49 000 000000 Hinter Tyler Smiths l\u00e4ssiger Surfer-Attit\u00fcde verbirgt sich eine starke Arbeitsmoral, die ihm weit \u00fcber das Haarstyling hinaus einen Namen gemacht hat. Galerie","og_url":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/","og_site_name":"Reutlingen | T\u00fcbingen | Stuttgart","article_modified_time":"2026-04-23T21:16:50+00:00","og_image":[{"width":540,"height":115,"url":"https:\/\/demos.infobd.de\/design4\/wp-content\/uploads\/sites\/8\/2024\/10\/demo-design-white.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/","url":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/","name":"Header Dark - Reutlingen | T\u00fcbingen | Stuttgart","isPartOf":{"@id":"https:\/\/demos.infobd.de\/design4\/#website"},"primaryImageOfPage":{"@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/#primaryimage"},"image":{"@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/#primaryimage"},"thumbnailUrl":"https:\/\/demos.infobd.de\/design4\/wp-content\/uploads\/sites\/8\/2024\/10\/demo-design-white.png","datePublished":"2024-10-07T10:13:50+00:00","dateModified":"2026-04-23T21:16:50+00:00","breadcrumb":{"@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/#primaryimage","url":"https:\/\/demos.infobd.de\/design4\/wp-content\/uploads\/sites\/8\/2024\/10\/demo-design-white.png","contentUrl":"https:\/\/demos.infobd.de\/design4\/wp-content\/uploads\/sites\/8\/2024\/10\/demo-design-white.png","width":540,"height":115},{"@type":"BreadcrumbList","@id":"https:\/\/demos.infobd.de\/design4\/wcf-template\/header-dark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demos.infobd.de\/design4\/"},{"@type":"ListItem","position":2,"name":"Header Dark"}]},{"@type":"WebSite","@id":"https:\/\/demos.infobd.de\/design4\/#website","url":"https:\/\/demos.infobd.de\/design4\/","name":"Reutlingen | T\u00fcbingen | Stuttgart","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demos.infobd.de\/design4\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/wcf-addons-template\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/wcf-addons-template"}],"about":[{"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/types\/wcf-addons-template"}],"version-history":[{"count":38,"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/wcf-addons-template\/278\/revisions"}],"predecessor-version":[{"id":2849,"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/wcf-addons-template\/278\/revisions\/2849"}],"wp:attachment":[{"href":"https:\/\/demos.infobd.de\/design4\/wp-json\/wp\/v2\/media?parent=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}