{"id":1983,"date":"2024-10-27T08:28:15","date_gmt":"2024-10-27T08:28:15","guid":{"rendered":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/"},"modified":"2024-12-08T05:59:38","modified_gmt":"2024-12-08T05:59:38","slug":"search-page","status":"publish","type":"wcf-addons-template","link":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/","title":{"rendered":"Search Page"},"featured_media":0,"template":"elementor_canvas","class_list":["post-1983","wcf-addons-template","type-wcf-addons-template","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Search Page - Law Farm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Search Page - Law Farm\" \/>\n<meta property=\"og:description\" content=\"Search Results for: Nothing found! It looks like nothing was found here. Maybe try a search? WealCoder October 22, 2024 Inside the courtroom: Libertylaw&#8217;s guide to criminal defense strategie WealCoder October 22, 2024 Navigating the dynamic legal landscape: Insights from Libertylaw WealCoder October 22, 2024 Corporate counsel corner: Libertylaw&#8217;s business law insights WealCoder October 22, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/\" \/>\n<meta property=\"og:site_name\" content=\"Law Farm\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-08T05:59:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/blog-6.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/\",\"name\":\"Search Page - Law Farm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/10\\\/blog-6.webp\",\"datePublished\":\"2024-10-27T08:28:15+00:00\",\"dateModified\":\"2024-12-08T05:59:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/#primaryimage\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/10\\\/blog-6.webp\",\"contentUrl\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/10\\\/blog-6.webp\",\"width\":600,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wcf-template\\\/search-page\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Search Page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#website\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/\",\"name\":\"Law Farm\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#organization\",\"name\":\"Law Farm\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/10\\\/site-logo.svg\",\"contentUrl\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/10\\\/site-logo.svg\",\"width\":84,\"height\":29,\"caption\":\"Law Farm\"},\"image\":{\"@id\":\"https:\\\/\\\/demos.infobd.de\\\/design10\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Search Page - Law Farm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/","og_locale":"en_US","og_type":"article","og_title":"Search Page - Law Farm","og_description":"Search Results for: Nothing found! It looks like nothing was found here. Maybe try a search? WealCoder October 22, 2024 Inside the courtroom: Libertylaw&#8217;s guide to criminal defense strategie WealCoder October 22, 2024 Navigating the dynamic legal landscape: Insights from Libertylaw WealCoder October 22, 2024 Corporate counsel corner: Libertylaw&#8217;s business law insights WealCoder October 22, [&hellip;]","og_url":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/","og_site_name":"Law Farm","article_modified_time":"2024-12-08T05:59:38+00:00","og_image":[{"width":600,"height":372,"url":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/blog-6.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/","url":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/","name":"Search Page - Law Farm","isPartOf":{"@id":"https:\/\/demos.infobd.de\/design10\/#website"},"primaryImageOfPage":{"@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/#primaryimage"},"image":{"@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/#primaryimage"},"thumbnailUrl":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/blog-6.webp","datePublished":"2024-10-27T08:28:15+00:00","dateModified":"2024-12-08T05:59:38+00:00","breadcrumb":{"@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/#primaryimage","url":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/blog-6.webp","contentUrl":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/blog-6.webp","width":600,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/demos.infobd.de\/design10\/wcf-template\/search-page\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demos.infobd.de\/design10\/"},{"@type":"ListItem","position":2,"name":"Search Page"}]},{"@type":"WebSite","@id":"https:\/\/demos.infobd.de\/design10\/#website","url":"https:\/\/demos.infobd.de\/design10\/","name":"Law Farm","description":"","publisher":{"@id":"https:\/\/demos.infobd.de\/design10\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demos.infobd.de\/design10\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/demos.infobd.de\/design10\/#organization","name":"Law Farm","url":"https:\/\/demos.infobd.de\/design10\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demos.infobd.de\/design10\/#\/schema\/logo\/image\/","url":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/site-logo.svg","contentUrl":"https:\/\/demos.infobd.de\/design10\/wp-content\/uploads\/sites\/14\/2024\/10\/site-logo.svg","width":84,"height":29,"caption":"Law Farm"},"image":{"@id":"https:\/\/demos.infobd.de\/design10\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/demos.infobd.de\/design10\/wp-json\/wp\/v2\/wcf-addons-template\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.infobd.de\/design10\/wp-json\/wp\/v2\/wcf-addons-template"}],"about":[{"href":"https:\/\/demos.infobd.de\/design10\/wp-json\/wp\/v2\/types\/wcf-addons-template"}],"version-history":[{"count":0,"href":"https:\/\/demos.infobd.de\/design10\/wp-json\/wp\/v2\/wcf-addons-template\/1983\/revisions"}],"wp:attachment":[{"href":"https:\/\/demos.infobd.de\/design10\/wp-json\/wp\/v2\/media?parent=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}